{"id":282031,"date":"2024-07-29T16:57:05","date_gmt":"2024-07-29T14:57:05","guid":{"rendered":"https:\/\/hf-solutions.co\/en\/?p=282031"},"modified":"2025-02-04T11:34:11","modified_gmt":"2025-02-04T10:34:11","slug":"member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions","status":"publish","type":"post","link":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/","title":{"rendered":"Member of the german Bundestag Tobias B. Bacherle in exchange with HF Solutions"},"content":{"rendered":"\n[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Sektion&#8221; module_class=&#8221;custom-post-header&#8221; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_post_title author=&#8221;off&#8221; date_format=&#8221;j m Y&#8221; comments=&#8221;off&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;60px||||false|false&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.26.1&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||16px|||&#8221; custom_padding=&#8221;32px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<h2><span class=\"EOP SCXW12075307 BCX8\" data-ccp-props=\"{\"><span class=\"NormalTextRun SCXW64095310 BCX8\">Member of the German Bundestag visits deep-tech company H&amp;F Solutions in Heilbronn<\/span><\/span><\/h2>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||2px|||&#8221; global_colors_info=&#8221;{}&#8221;]<p>Tobias B. Bacherle visited H&amp;F Solutions GmbH in the Campus Founders co-working space in Heilbronn as part of this year&#8217;s &#8220;CyberL\u00c4ND&#8221; summer tour through Baden-W\u00fcrttemberg. Mr. Bacherle has been a member of the 20th German Bundestag for B\u00fcndnis 90\/Die Gr\u00fcnen and the B\u00f6blingen constituency since 2021 and, as chairman of the Committee on Digital Affairs and member of the Committee on Foreign Affairs, is committed to a value-based foreign policy, digitalization and innovation. His main areas of focus include the national <br \/>and international handling of artificial intelligence (AI) and data policy.<\/p>\n<p>With this in mind, an exchange between Mr. Bacherle, H&amp;F Solutions and Campus Founders took place at the Heilbronn education campus. The event focused on the current challenges of digitalization, particularly for start-ups in the Heilbronn ecosystem and at a political level. Key points on the agenda included the Data Protection Act and data access and usage rights in a business context, as well as the associated political challenges. The topic of occupational health and safety law was also discussed.<\/p>\n<p>The need to expand renewable energies in the form of wind farms was also addressed. All participants agreed that Germany needs electricity in the context of digitalization, but that this should ideally come from renewable sources. The program was complemented by presentations by Florian Kratz (Head of Brand &amp; Marketing, Campus Founders), who provided information about the Heilbronn ecosystem and the key role of Campus Founders. Philipp Futterknecht (CEO, H&amp;F Solutions) and Hans-J\u00f6rg Roser (CPO, H&amp;F Solutions), on the other hand, discussed the cloud software dara\u00ae, which enables the automated exchange of documents between companies. Throughout the visit, Mr. Bacherle showed great interest in the concerns of those present and was always available to answer questions and make suggestions to politicians.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>In Heilbronn, HF Solutions welcomed Tobias B. Bacherle (B\u00fcndnis 90\/Die Gr\u00fcnen), member of the german Bundestag, to discuss digitalization issues with him and the Campus Founders. <\/p>\n","protected":false},"author":8,"featured_media":282038,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[10,11,12,13,15,19,20,16,21,17,18],"class_list":["post-282031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-innovation-en","tag-edi-en","tag-edi-schnittstelle-en","tag-erp-en","tag-idi-en","tag-intelligent-data-interchange-en","tag-intelligent-data-interchange","tag-intelligenter-datenaustausch","tag-intelligenter-datenaustausch-en","tag-nachhaltigkeit","tag-ocr-en","tag-rpa-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Member of the german Bundestag Tobias B. Bacherle in exchange with HF Solutions - H&amp;F Solutions<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Member of the german Bundestag Tobias B. Bacherle in exchange with HF Solutions - H&amp;F Solutions\" \/>\n<meta property=\"og:description\" content=\"In Heilbronn, HF Solutions welcomed Tobias B. Bacherle (B\u00fcndnis 90\/Die Gr\u00fcnen), member of the german Bundestag, to discuss digitalization issues with him and the Campus Founders.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/\" \/>\n<meta property=\"og:site_name\" content=\"H&amp;F Solutions\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/handfsolutions\/?locale=de_DE\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-29T14:57:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-04T10:34:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/neu.hf-solutions.co\/en\/wp-content\/uploads\/sites\/2\/2024\/07\/Anzeigebild-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hanna Mayer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hanna Mayer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/2024\\\/07\\\/29\\\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/2024\\\/07\\\/29\\\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\\\/\"},\"author\":{\"name\":\"Hanna Mayer\",\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/#\\\/schema\\\/person\\\/c97bfecacab54dec8d9248098b820a70\"},\"headline\":\"Member of the german Bundestag Tobias B. Bacherle in exchange with HF Solutions\",\"datePublished\":\"2024-07-29T14:57:05+00:00\",\"dateModified\":\"2025-02-04T10:34:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/2024\\\/07\\\/29\\\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\\\/\"},\"wordCount\":518,\"publisher\":{\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/2024\\\/07\\\/29\\\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/Anzeigebild-1-1.jpg\",\"keywords\":[\"EDI\",\"EDI-Schnittstelle\",\"ERP\",\"IDI\",\"Intelligent Data Interchange\",\"Intelligent Data Interchange\",\"intelligenter Datenaustausch\",\"intelligenter Datenaustausch\",\"Nachhaltigkeit\",\"OCR\",\"RPA\"],\"articleSection\":[\"Innovation\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/2024\\\/07\\\/29\\\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\\\/\",\"url\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/2024\\\/07\\\/29\\\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\\\/\",\"name\":\"Member of the german Bundestag Tobias B. Bacherle in exchange with HF Solutions - H&amp;F Solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/2024\\\/07\\\/29\\\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/2024\\\/07\\\/29\\\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/Anzeigebild-1-1.jpg\",\"datePublished\":\"2024-07-29T14:57:05+00:00\",\"dateModified\":\"2025-02-04T10:34:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/2024\\\/07\\\/29\\\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/2024\\\/07\\\/29\\\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/2024\\\/07\\\/29\\\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/Anzeigebild-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/Anzeigebild-1-1.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/2024\\\/07\\\/29\\\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Member of the german Bundestag Tobias B. Bacherle in exchange with HF Solutions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/\",\"name\":\"H&F Solutions\",\"description\":\"Fully Automated B2B Document Exchange\",\"publisher\":{\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/#organization\",\"name\":\"H&F Solutions\",\"url\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/02\\\/dara-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/02\\\/dara-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"H&F Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/handfsolutions\\\/?locale=de_DE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/#\\\/schema\\\/person\\\/c97bfecacab54dec8d9248098b820a70\",\"name\":\"Hanna Mayer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f8185575f0816c61ae68e25ad85a58040a5b21920afd3b612cbdf08db5dcbd9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f8185575f0816c61ae68e25ad85a58040a5b21920afd3b612cbdf08db5dcbd9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f8185575f0816c61ae68e25ad85a58040a5b21920afd3b612cbdf08db5dcbd9?s=96&d=mm&r=g\",\"caption\":\"Hanna Mayer\"},\"url\":\"https:\\\/\\\/neu.hf-solutions.co\\\/en\\\/blog\\\/author\\\/hanna-mayer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Member of the german Bundestag Tobias B. Bacherle in exchange with HF Solutions - H&amp;F Solutions","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Member of the german Bundestag Tobias B. Bacherle in exchange with HF Solutions - H&amp;F Solutions","og_description":"In Heilbronn, HF Solutions welcomed Tobias B. Bacherle (B\u00fcndnis 90\/Die Gr\u00fcnen), member of the german Bundestag, to discuss digitalization issues with him and the Campus Founders.","og_url":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/","og_site_name":"H&amp;F Solutions","article_publisher":"https:\/\/www.facebook.com\/handfsolutions\/?locale=de_DE","article_published_time":"2024-07-29T14:57:05+00:00","article_modified_time":"2025-02-04T10:34:11+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/neu.hf-solutions.co\/en\/wp-content\/uploads\/sites\/2\/2024\/07\/Anzeigebild-1-1.jpg","type":"image\/jpeg"}],"author":"Hanna Mayer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Hanna Mayer","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/#article","isPartOf":{"@id":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/"},"author":{"name":"Hanna Mayer","@id":"https:\/\/neu.hf-solutions.co\/en\/#\/schema\/person\/c97bfecacab54dec8d9248098b820a70"},"headline":"Member of the german Bundestag Tobias B. Bacherle in exchange with HF Solutions","datePublished":"2024-07-29T14:57:05+00:00","dateModified":"2025-02-04T10:34:11+00:00","mainEntityOfPage":{"@id":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/"},"wordCount":518,"publisher":{"@id":"https:\/\/neu.hf-solutions.co\/en\/#organization"},"image":{"@id":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/#primaryimage"},"thumbnailUrl":"https:\/\/neu.hf-solutions.co\/en\/wp-content\/uploads\/sites\/2\/2024\/07\/Anzeigebild-1-1.jpg","keywords":["EDI","EDI-Schnittstelle","ERP","IDI","Intelligent Data Interchange","Intelligent Data Interchange","intelligenter Datenaustausch","intelligenter Datenaustausch","Nachhaltigkeit","OCR","RPA"],"articleSection":["Innovation"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/","url":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/","name":"Member of the german Bundestag Tobias B. Bacherle in exchange with HF Solutions - H&amp;F Solutions","isPartOf":{"@id":"https:\/\/neu.hf-solutions.co\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/#primaryimage"},"image":{"@id":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/#primaryimage"},"thumbnailUrl":"https:\/\/neu.hf-solutions.co\/en\/wp-content\/uploads\/sites\/2\/2024\/07\/Anzeigebild-1-1.jpg","datePublished":"2024-07-29T14:57:05+00:00","dateModified":"2025-02-04T10:34:11+00:00","breadcrumb":{"@id":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/#primaryimage","url":"https:\/\/neu.hf-solutions.co\/en\/wp-content\/uploads\/sites\/2\/2024\/07\/Anzeigebild-1-1.jpg","contentUrl":"https:\/\/neu.hf-solutions.co\/en\/wp-content\/uploads\/sites\/2\/2024\/07\/Anzeigebild-1-1.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/neu.hf-solutions.co\/en\/blog\/2024\/07\/29\/member-of-the-german-bundestag-tobias-b-bacherle-in-exchange-with-hf-solutions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/neu.hf-solutions.co\/en\/"},{"@type":"ListItem","position":2,"name":"Member of the german Bundestag Tobias B. Bacherle in exchange with HF Solutions"}]},{"@type":"WebSite","@id":"https:\/\/neu.hf-solutions.co\/en\/#website","url":"https:\/\/neu.hf-solutions.co\/en\/","name":"H&F Solutions","description":"Fully Automated B2B Document Exchange","publisher":{"@id":"https:\/\/neu.hf-solutions.co\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/neu.hf-solutions.co\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/neu.hf-solutions.co\/en\/#organization","name":"H&F Solutions","url":"https:\/\/neu.hf-solutions.co\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/neu.hf-solutions.co\/en\/#\/schema\/logo\/image\/","url":"https:\/\/neu.hf-solutions.co\/en\/wp-content\/uploads\/sites\/2\/2025\/02\/dara-696x696-1.jpg","contentUrl":"https:\/\/neu.hf-solutions.co\/en\/wp-content\/uploads\/sites\/2\/2025\/02\/dara-696x696-1.jpg","width":696,"height":696,"caption":"H&F Solutions"},"image":{"@id":"https:\/\/neu.hf-solutions.co\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/handfsolutions\/?locale=de_DE"]},{"@type":"Person","@id":"https:\/\/neu.hf-solutions.co\/en\/#\/schema\/person\/c97bfecacab54dec8d9248098b820a70","name":"Hanna Mayer","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/1f8185575f0816c61ae68e25ad85a58040a5b21920afd3b612cbdf08db5dcbd9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f8185575f0816c61ae68e25ad85a58040a5b21920afd3b612cbdf08db5dcbd9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f8185575f0816c61ae68e25ad85a58040a5b21920afd3b612cbdf08db5dcbd9?s=96&d=mm&r=g","caption":"Hanna Mayer"},"url":"https:\/\/neu.hf-solutions.co\/en\/blog\/author\/hanna-mayer\/"}]}},"_links":{"self":[{"href":"https:\/\/neu.hf-solutions.co\/en\/wp-json\/wp\/v2\/posts\/282031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neu.hf-solutions.co\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neu.hf-solutions.co\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neu.hf-solutions.co\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/neu.hf-solutions.co\/en\/wp-json\/wp\/v2\/comments?post=282031"}],"version-history":[{"count":1,"href":"https:\/\/neu.hf-solutions.co\/en\/wp-json\/wp\/v2\/posts\/282031\/revisions"}],"predecessor-version":[{"id":283919,"href":"https:\/\/neu.hf-solutions.co\/en\/wp-json\/wp\/v2\/posts\/282031\/revisions\/283919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/neu.hf-solutions.co\/en\/wp-json\/wp\/v2\/media\/282038"}],"wp:attachment":[{"href":"https:\/\/neu.hf-solutions.co\/en\/wp-json\/wp\/v2\/media?parent=282031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neu.hf-solutions.co\/en\/wp-json\/wp\/v2\/categories?post=282031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neu.hf-solutions.co\/en\/wp-json\/wp\/v2\/tags?post=282031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}